{"id":5093,"date":"2022-01-12T16:18:50","date_gmt":"2022-01-12T16:18:50","guid":{"rendered":"https:\/\/www.daldewolf.com\/foreign-investment-negative-list\/"},"modified":"2022-01-13T16:55:06","modified_gmt":"2022-01-13T16:55:06","slug":"liste-negative-des-investissements-etrangers-de-la-chine","status":"publish","type":"post","link":"https:\/\/www.daldewolf.com\/fr\/liste-negative-des-investissements-etrangers-de-la-chine\/","title":{"rendered":"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers"},"content":{"rendered":"<p><strong>La veille de No\u00ebl, la Chine a publi\u00e9 un projet d&#8217;amendement \u00e0 la loi sur les soci\u00e9t\u00e9s de la RPC \u00e0 l&#8217;intention du public, et juste apr\u00e8s le week-end de No\u00ebl, le 27 d\u00e9cembre 2021, la Commission nationale du d\u00e9veloppement et de la r\u00e9forme (CNDR) et le minist\u00e8re du commerce (MDC) ont publi\u00e9 conjointement une mise \u00e0 jour des mesures administratives sp\u00e9ciales pour l&#8217;acc\u00e8s aux investissements \u00e9trangers (c&#8217;est-\u00e0-dire, plus couramment d\u00e9nomm\u00e9e la liste n\u00e9gative des investissements \u00e9trangers), qui r\u00e9glemente l&#8217;acc\u00e8s des investissements \u00e9trangers en Chine.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-5065 size-medium\" src=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04-300x300.jpg\" alt=\"Nouvelle liste n\u00e9gative des investissements \u00e9trangers de la Chine\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04-300x300.jpg 300w, https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04-1024x1024.jpg 1024w, https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04-150x150.jpg 150w, https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04-600x600.jpg 600w, https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"color: #bc8422;\"><strong>LISTE N\u00c9GATIVE<\/strong><\/span><br \/>\nL&#8217;acc\u00e8s des investissements \u00e9trangers en Chine est principalement r\u00e9glement\u00e9 par la liste n\u00e9gative des investissements \u00e9trangers (la \u00ab Liste N\u00e9gative \u00bb). Les secteurs industriels figurant sur cette liste sont soit interdits aux investissements \u00e9trangers, soit soumis \u00e0 certaines limitations (par exemple, aucune participation majoritaire ne peut \u00eatre d\u00e9tenue par un investisseur \u00e9tranger). Tout secteur qui ne figure pas sur la Liste N\u00e9gative peut \u00eatre accessible aux investisseurs \u00e9trangers selon les m\u00eames r\u00e8gles et r\u00e9glementations que celles applicables aux investisseurs nationaux chinois.<\/p>\n<p>Il existe en fait deux listes n\u00e9gatives en vigueur : l&#8217;une applicable \u00e0 toutes les zones g\u00e9ographiques de la R\u00e9publique populaire de Chine (la \u00ab Liste n\u00e9gative nationale \u00bb), l&#8217;autre applicable aux zones pilotes de libre-\u00e9change uniquement (c&#8217;est-\u00e0-dire les zones sp\u00e9ciales o\u00f9 les politiques et r\u00e9glementations pr\u00e9f\u00e9rentielles sur les investissements \u00e9trangers sont accord\u00e9es) (la \u00ab Liste n\u00e9gative pour les zones pilotes de libre-\u00e9change \u00bb).<\/p>\n<p><span style=\"color: #bc8422;\"><strong>LA LISTE N\u00c9GATIVE EST ENTR\u00c9E EN VIGUEUR LE 01\/01\/2022<\/strong><\/span><br \/>\nLa nouvelle Liste N\u00e9gative (\u00e9dition 2021, voir le Communiqu\u00e9 en Chinois : <a href=\"http:\/\/www.mofcom.gov.cn\/article\/xwfb\/xwrcxw\/202112\/20211203232113.shtml\">\u56fd\u5bb6\u53d1\u5c55\u6539\u9769\u59d4 \u5546\u52a1\u90e8\u53d1\u5e032021\u5e74\u7248\u5916\u8d44\u51c6\u5165\u8d1f\u9762\u6e05\u5355 (mofcom.gov.cn)<\/a> ) est entr\u00e9e en vigueur le 1er janvier 2022. Il s&#8217;agit de la quatri\u00e8me version depuis la premi\u00e8re publication de la Liste N\u00e9gative en 2018.<\/p>\n<p>Par rapport \u00e0 l&#8217;\u00e9dition 2020, les secteurs de la Liste n\u00e9gative nationale ont \u00e9t\u00e9 continuellement r\u00e9duits de 33 \u00e0 31, ceux figurant sur la Liste n\u00e9gative pour les zones pilotes de libre-\u00e9change ont \u00e9t\u00e9 r\u00e9duits \u00e0 27 secteurs.<\/p>\n<p>Les changements significatifs les plus importants sont les suivants :<\/p>\n<h3 style=\"padding-left: 40px;\">1. Lib\u00e9ration totale de l&#8217;ACC\u00c8S des investisseurs \u00e9trangers dans le secteur de la construction automobile<\/h3>\n<p style=\"padding-left: 40px;\">Tant dans la Liste n\u00e9gative nationale que dans la Liste n\u00e9gative pour les zones pilotes de libre-\u00e9change, les investisseurs \u00e9trangers ne sont pas soumis \u00e0 la restriction de participation maximale de 50 % dans le secteur de la fabrication de v\u00e9hicules priv\u00e9s en Chine.<br \/>\nIl n&#8217;y a \u00e9galement plus de limitation sur le nombre de joint-ventures qu&#8217;un investisseur \u00e9tranger peut conclure dans ce secteur.<br \/>\nCela signifie qu&#8217;\u00e0 partir de maintenant, il n&#8217;y a plus de limitation \u00e0 l&#8217;acc\u00e8s des investisseurs \u00e9trangers dans le secteur automobile en Chine. Les constructeurs automobiles europ\u00e9ens ne sont plus l\u00e9galement tenus d&#8217;avoir un partenaire chinois pour acc\u00e9der \u00e0 ce secteur.<\/p>\n<h3 style=\"padding-left: 40px;\">2. Poursuite de l&#8217;ouverture du secteur des services commerciaux<\/h3>\n<p style=\"padding-left: 40px;\">Dans la liste n\u00e9gative pour les zones pilotes de libre-\u00e9change, les restrictions d&#8217;acc\u00e8s aux investissements \u00e9trangers dans le domaine des \u00e9tudes de march\u00e9 ont \u00e9t\u00e9 supprim\u00e9es.<\/p>\n<p style=\"padding-left: 40px;\">Cependant, en ce qui concerne le secteur des enqu\u00eates sociales, l&#8217;investissement \u00e9tranger est autoris\u00e9 mais il n\u00e9cessite toujours une participation chinoise d&#8217;au moins 67%, et le repr\u00e9sentant l\u00e9gal doit avoir la nationalit\u00e9 chinoise.<\/p>\n<h3 style=\"padding-left: 40px;\">3.\u00a0Les introductions en bourse \u00e0 l&#8217;\u00e9tranger d&#8217;entreprises chinoises des secteurs interdits aux investissements \u00e9trangers doivent obtenir une approbation pr\u00e9alable<\/h3>\n<p style=\"padding-left: 40px;\">La note explicative de la Liste N\u00e9gative stipule \u00e9galement de mani\u00e8re explicite que toute entreprise chinoise impliqu\u00e9e dans des secteurs non ouverts aux investissements \u00e9trangers doit au pr\u00e9alable obtenir l&#8217;approbation du gouvernement chaque fois qu&#8217;elle souhaite inscrire tout ou partie de ses actions sur une bourse hors de la R\u00e9publique populaire de Chine. De plus, les investisseurs \u00e9trangers ne peuvent pas participer \u00e0 la gestion de ces soci\u00e9t\u00e9s..<\/p>\n<p>Pour plus d&#8217;information sur la nouvelle liste n\u00e9gative des investissements \u00e9trangers de la Chine, veuillez contacter <a href=\"https:\/\/www.daldewolf.com\/en\/team\/tu-xiufang-ava\/\">Xiufang (Ava) TU<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La veille de No\u00ebl, la Chine a publi\u00e9 un projet d&#8217;amendement \u00e0 la loi sur les soci\u00e9t\u00e9s de la RPC \u00e0 l&#8217;intention du public, et juste apr\u00e8s le week-end de No\u00ebl, le 27 d\u00e9cembre 2021, la Commission nationale du d\u00e9veloppement et de la r\u00e9forme (CNDR) et le minist\u00e8re du commerce (MDC) ont publi\u00e9 conjointement une&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44,58],"tags":[],"class_list":["post-5093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowhow","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liste n\u00e9gative des investissements \u00e9trangers - Desk Chine - DALDEWOLF<\/title>\n<meta name=\"description\" content=\"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers. Un article par Xiufang (Ava) TU, Counsel chez DALDEWOLF, Responsable du Desk Chine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liste n\u00e9gative des investissements \u00e9trangers - Desk Chine - DALDEWOLF\" \/>\n<meta property=\"og:description\" content=\"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers. Un article par Xiufang (Ava) TU, Counsel chez DALDEWOLF, Responsable du Desk Chine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/\" \/>\n<meta property=\"og:site_name\" content=\"DALDEWOLF\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T16:18:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-13T16:55:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"daldewolf-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"daldewolf-admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/\"},\"author\":{\"name\":\"daldewolf-admin\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/person\\\/2b729bb994cea798211b29fbabbbac1e\"},\"headline\":\"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers\",\"datePublished\":\"2022-01-12T16:18:50+00:00\",\"dateModified\":\"2022-01-13T16:55:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/\"},\"wordCount\":704,\"publisher\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ava_newletter_linkedin_04.jpg\",\"articleSection\":[\"knowhow\",\"news\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/\",\"name\":\"Liste n\u00e9gative des investissements \u00e9trangers - Desk Chine - DALDEWOLF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ava_newletter_linkedin_04.jpg\",\"datePublished\":\"2022-01-12T16:18:50+00:00\",\"dateModified\":\"2022-01-13T16:55:06+00:00\",\"description\":\"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers. Un article par Xiufang (Ava) TU, Counsel chez DALDEWOLF, Responsable du Desk Chine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ava_newletter_linkedin_04.jpg\",\"contentUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ava_newletter_linkedin_04.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Newly released China's foreign investment negative list - DALDEWOLF China Desk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/foreign-investment-negative-list\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/\",\"name\":\"DALDEWOLF\",\"description\":\"Independant Law firm, Since 1958.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\",\"name\":\"DALDEWOLF\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Daldewolf.png\",\"contentUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Daldewolf.png\",\"width\":320,\"height\":40,\"caption\":\"DALDEWOLF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10193320\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/person\\\/2b729bb994cea798211b29fbabbbac1e\",\"name\":\"daldewolf-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g\",\"caption\":\"daldewolf-admin\"},\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/author\\\/daldewolf-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liste n\u00e9gative des investissements \u00e9trangers - Desk Chine - DALDEWOLF","description":"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers. Un article par Xiufang (Ava) TU, Counsel chez DALDEWOLF, Responsable du Desk Chine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/","og_locale":"fr_FR","og_type":"article","og_title":"Liste n\u00e9gative des investissements \u00e9trangers - Desk Chine - DALDEWOLF","og_description":"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers. Un article par Xiufang (Ava) TU, Counsel chez DALDEWOLF, Responsable du Desk Chine.","og_url":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/","og_site_name":"DALDEWOLF","article_published_time":"2022-01-12T16:18:50+00:00","article_modified_time":"2022-01-13T16:55:06+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg","type":"image\/jpeg"}],"author":"daldewolf-admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"daldewolf-admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#article","isPartOf":{"@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/"},"author":{"name":"daldewolf-admin","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/person\/2b729bb994cea798211b29fbabbbac1e"},"headline":"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers","datePublished":"2022-01-12T16:18:50+00:00","dateModified":"2022-01-13T16:55:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/"},"wordCount":704,"publisher":{"@id":"https:\/\/www.daldewolf.com\/nl\/#organization"},"image":{"@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#primaryimage"},"thumbnailUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg","articleSection":["knowhow","news"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/","url":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/","name":"Liste n\u00e9gative des investissements \u00e9trangers - Desk Chine - DALDEWOLF","isPartOf":{"@id":"https:\/\/www.daldewolf.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#primaryimage"},"image":{"@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#primaryimage"},"thumbnailUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg","datePublished":"2022-01-12T16:18:50+00:00","dateModified":"2022-01-13T16:55:06+00:00","description":"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers. Un article par Xiufang (Ava) TU, Counsel chez DALDEWOLF, Responsable du Desk Chine.","breadcrumb":{"@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#primaryimage","url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg","contentUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2022\/01\/ava_newletter_linkedin_04.jpg","width":1200,"height":1200,"caption":"Newly released China's foreign investment negative list - DALDEWOLF China Desk"},{"@type":"BreadcrumbList","@id":"https:\/\/www.daldewolf.com\/en\/foreign-investment-negative-list\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.daldewolf.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La Chine a r\u00e9cemment publi\u00e9 sa liste n\u00e9gative des investissements \u00e9trangers"}]},{"@type":"WebSite","@id":"https:\/\/www.daldewolf.com\/nl\/#website","url":"https:\/\/www.daldewolf.com\/nl\/","name":"DALDEWOLF","description":"Independant Law firm, Since 1958.","publisher":{"@id":"https:\/\/www.daldewolf.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.daldewolf.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.daldewolf.com\/nl\/#organization","name":"DALDEWOLF","url":"https:\/\/www.daldewolf.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/Logo-Daldewolf.png","contentUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/Logo-Daldewolf.png","width":320,"height":40,"caption":"DALDEWOLF"},"image":{"@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/10193320"]},{"@type":"Person","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/person\/2b729bb994cea798211b29fbabbbac1e","name":"daldewolf-admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g","caption":"daldewolf-admin"},"url":"https:\/\/www.daldewolf.com\/fr\/author\/daldewolf-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/posts\/5093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/comments?post=5093"}],"version-history":[{"count":0,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/posts\/5093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/media\/5067"}],"wp:attachment":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/media?parent=5093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/categories?post=5093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/tags?post=5093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}