{"id":3975,"date":"2021-05-25T13:02:16","date_gmt":"2021-05-25T13:02:16","guid":{"rendered":"https:\/\/www.daldewolf.com\/?p=3975"},"modified":"2021-06-01T08:58:21","modified_gmt":"2021-06-01T08:58:21","slug":"droit-alimentaire-un-webinaire-qui-aura-lieu-le-3-juin-2021","status":"publish","type":"post","link":"https:\/\/www.daldewolf.com\/fr\/droit-alimentaire-un-webinaire-qui-aura-lieu-le-3-juin-2021\/","title":{"rendered":"Droit alimentaire &#8211; Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage"},"content":{"rendered":"<p>Le 3 juin 2021, Aude Mahy fera un expos\u00e9 \u2013 \u00ab\u00a0Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage\u00a0\u00bb\u00a0&#8211; lors d\u2019une rencontre d\u2019information organis\u00e9e, sous la forme d\u2019un webinaire par Qu\u00e9bec International et le Cr\u00e9neau Aliments Sant\u00e9, en collaboration avec la D\u00e9l\u00e9gation g\u00e9n\u00e9rale du Qu\u00e9bec. Ce webinaire pr\u00e9sentera les opportunit\u00e9s dans le secteur bioalimentaire au Benelux, ainsi que les d\u00e9fis li\u00e9s \u00e0 l\u2019exportation.<\/p>\n<p><a href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.quebecinternational.ca%2Ffr%2Fevenements%2Finscription-benelux-porte-dentree-de-leurope-pour-les-entreprises-bioalimentaires-151218339123&amp;data=04%7C01%7Cknowhow%40daldewolf.com%7C54c0e568c143469594b008d91f60687a%7Cf6732aa93d3f4b82b5b4b1b1e5c25628%7C0%7C0%7C637575321195089347%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=IuB%2BKIXbQ8KGENuPnS0VsVbhr4kS%2BdkTLTjXA28yZ6M%3D&amp;reserved=0\">https:\/\/www.quebecinternational.ca\/fr\/evenements\/inscription-benelux-porte-dentree-de-leurope-pour-les-entreprises-bioalimentaires-151218339123<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1614\" src=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg\" alt=\"\" width=\"224\" height=\"149\" srcset=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg 300w, https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-1024x683.jpg 1024w, https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-391x260.jpg 391w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 3 juin 2021, Aude Mahy fera un expos\u00e9 \u2013 \u00ab\u00a0Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage\u00a0\u00bb\u00a0&#8211; lors d\u2019une rencontre d\u2019information organis\u00e9e, sous la forme d\u2019un webinaire par Qu\u00e9bec International et le Cr\u00e9neau Aliments Sant\u00e9, en collaboration avec la D\u00e9l\u00e9gation g\u00e9n\u00e9rale du Qu\u00e9bec. Ce webinaire pr\u00e9sentera les opportunit\u00e9s dans le secteur bioalimentaire au Benelux,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44,58],"tags":[],"class_list":["post-3975","post","type-post","status-publish","format-standard","hentry","category-knowhow","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Droit alimentaire - Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en - R\u00e9glementation et \u00e9tiquetage - DALDEWOLF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Droit alimentaire - Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en - R\u00e9glementation et \u00e9tiquetage - DALDEWOLF\" \/>\n<meta property=\"og:description\" content=\"Le 3 juin 2021, Aude Mahy fera un expos\u00e9 \u2013 \u00ab\u00a0Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage\u00a0\u00bb\u00a0&#8211; lors d\u2019une rencontre d\u2019information organis\u00e9e, sous la forme d\u2019un webinaire par Qu\u00e9bec International et le Cr\u00e9neau Aliments Sant\u00e9, en collaboration avec la D\u00e9l\u00e9gation g\u00e9n\u00e9rale du Qu\u00e9bec. Ce webinaire pr\u00e9sentera les opportunit\u00e9s dans le secteur bioalimentaire au Benelux,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"DALDEWOLF\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-25T13:02:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-01T08:58:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg\" \/>\n<meta name=\"author\" content=\"daldewolf-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"daldewolf-admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/\"},\"author\":{\"name\":\"daldewolf-admin\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/person\\\/2b729bb994cea798211b29fbabbbac1e\"},\"headline\":\"Droit alimentaire &#8211; Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage\",\"datePublished\":\"2021-05-25T13:02:16+00:00\",\"dateModified\":\"2021-06-01T08:58:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/\"},\"wordCount\":103,\"publisher\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MAHY-Aude-1-300x200.jpg\",\"articleSection\":[\"knowhow\",\"news\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/\",\"name\":\"Droit alimentaire - Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en - R\u00e9glementation et \u00e9tiquetage - DALDEWOLF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MAHY-Aude-1-300x200.jpg\",\"datePublished\":\"2021-05-25T13:02:16+00:00\",\"dateModified\":\"2021-06-01T08:58:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MAHY-Aude-1-300x200.jpg\",\"contentUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/MAHY-Aude-1-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/en\\\/food-law-a-webinar-that-will-take-place-on-3-june-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Droit alimentaire &#8211; Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/\",\"name\":\"DALDEWOLF\",\"description\":\"Independant Law firm, Since 1958.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\",\"name\":\"DALDEWOLF\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Daldewolf.png\",\"contentUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Daldewolf.png\",\"width\":320,\"height\":40,\"caption\":\"DALDEWOLF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10193320\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/person\\\/2b729bb994cea798211b29fbabbbac1e\",\"name\":\"daldewolf-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g\",\"caption\":\"daldewolf-admin\"},\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/author\\\/daldewolf-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Droit alimentaire - Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en - R\u00e9glementation et \u00e9tiquetage - DALDEWOLF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Droit alimentaire - Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en - R\u00e9glementation et \u00e9tiquetage - DALDEWOLF","og_description":"Le 3 juin 2021, Aude Mahy fera un expos\u00e9 \u2013 \u00ab\u00a0Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage\u00a0\u00bb\u00a0&#8211; lors d\u2019une rencontre d\u2019information organis\u00e9e, sous la forme d\u2019un webinaire par Qu\u00e9bec International et le Cr\u00e9neau Aliments Sant\u00e9, en collaboration avec la D\u00e9l\u00e9gation g\u00e9n\u00e9rale du Qu\u00e9bec. Ce webinaire pr\u00e9sentera les opportunit\u00e9s dans le secteur bioalimentaire au Benelux,...","og_url":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/","og_site_name":"DALDEWOLF","article_published_time":"2021-05-25T13:02:16+00:00","article_modified_time":"2021-06-01T08:58:21+00:00","og_image":[{"url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg","type":"","width":"","height":""}],"author":"daldewolf-admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"daldewolf-admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#article","isPartOf":{"@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/"},"author":{"name":"daldewolf-admin","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/person\/2b729bb994cea798211b29fbabbbac1e"},"headline":"Droit alimentaire &#8211; Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage","datePublished":"2021-05-25T13:02:16+00:00","dateModified":"2021-06-01T08:58:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/"},"wordCount":103,"publisher":{"@id":"https:\/\/www.daldewolf.com\/nl\/#organization"},"image":{"@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg","articleSection":["knowhow","news"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/","url":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/","name":"Droit alimentaire - Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en - R\u00e9glementation et \u00e9tiquetage - DALDEWOLF","isPartOf":{"@id":"https:\/\/www.daldewolf.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg","datePublished":"2021-05-25T13:02:16+00:00","dateModified":"2021-06-01T08:58:21+00:00","breadcrumb":{"@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#primaryimage","url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg","contentUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/MAHY-Aude-1-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.daldewolf.com\/en\/food-law-a-webinar-that-will-take-place-on-3-june-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.daldewolf.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Droit alimentaire &#8211; Webinaire du 3 juin 2021: Acc\u00e8s au march\u00e9 europ\u00e9en &#8211; R\u00e9glementation et \u00e9tiquetage"}]},{"@type":"WebSite","@id":"https:\/\/www.daldewolf.com\/nl\/#website","url":"https:\/\/www.daldewolf.com\/nl\/","name":"DALDEWOLF","description":"Independant Law firm, Since 1958.","publisher":{"@id":"https:\/\/www.daldewolf.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.daldewolf.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.daldewolf.com\/nl\/#organization","name":"DALDEWOLF","url":"https:\/\/www.daldewolf.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/Logo-Daldewolf.png","contentUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/Logo-Daldewolf.png","width":320,"height":40,"caption":"DALDEWOLF"},"image":{"@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/10193320"]},{"@type":"Person","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/person\/2b729bb994cea798211b29fbabbbac1e","name":"daldewolf-admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/752e94ee65450d9bac4adf789cbc1dfd0a1cca5f51532f1c021a33c89eb4bbaf?s=96&d=mm&r=g","caption":"daldewolf-admin"},"url":"https:\/\/www.daldewolf.com\/fr\/author\/daldewolf-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/posts\/3975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/comments?post=3975"}],"version-history":[{"count":0,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/posts\/3975\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/media?parent=3975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/categories?post=3975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/tags?post=3975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}