{"id":15596,"date":"2024-10-14T17:45:03","date_gmt":"2024-10-14T15:45:03","guid":{"rendered":"https:\/\/www.daldewolf.com\/daldewolf-en-rdc-conditions-generales\/"},"modified":"2024-10-15T11:49:01","modified_gmt":"2024-10-15T09:49:01","slug":"daldewolf-en-rdc-conditions-generales","status":"publish","type":"page","link":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/","title":{"rendered":"DALDEWOLF en RDC &#8211; Conditions G\u00e9n\u00e9rales"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-4 wpb_column vc_column_container first-column-sp\"><div class=\"vc_column-inner type_sticky\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">\u00c0 PROPOS DE<br \/>\nDALDEWOLF EN RDC<\/h2>\n<\/div><\/div><nav class=\"w-menu us_custom_3c67a9ec layout_ver style_links us_menu_1\" style=\"--main-gap:1.5rem;--main-ver-indent:0.8em;--main-hor-indent:0.8em;--main-color:inherit;\" id=\"menu\"><ul id=\"menu-ddw-rdc\" class=\"menu\"><li id=\"menu-item-15632\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15632\"><a href=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-le-cabinet\/\">Le cabinet et son approche<\/a><\/li><li id=\"menu-item-15630\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15630\"><a href=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-comment-nous-pouvons-aider\/\">Comment nous pouvons aider<\/a><\/li><li id=\"menu-item-15631\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15631\"><a href=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-lequipe\/\">L\u2019\u00e9quipe<\/a><\/li><li id=\"menu-item-15628\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15628\"><a href=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-contact\/\">Contact<\/a><\/li><li id=\"menu-item-15629\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15629\"><a href=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/\">Conditions g\u00e9n\u00e9rales<\/a><\/li><\/ul><style>@media ( max-width:600px ){.us_menu_1 .menu{display:block!important}.us_menu_1 .menu>li:not(:last-child){margin:0 0 var(--main-gap,1.5rem)!important}}<\/style><\/nav><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">AUTRES PAYS AFRICAINS<\/h2>\n<\/div><\/div><nav class=\"w-menu us_custom_3c67a9ec layout_ver style_links us_menu_2\" style=\"--main-gap:1.5rem;--main-ver-indent:0.8em;--main-hor-indent:0.8em;--main-color:inherit;\"><ul id=\"menu-autres-pays-africains\" class=\"menu\"><li id=\"menu-item-15633\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15633\"><a href=\"https:\/\/www.daldewolf.com\/fr\/autres-pays-africains-contact\/\">Contact<\/a><\/li><\/ul><style>@media ( max-width:600px ){.us_menu_2 .menu{display:block!important}.us_menu_2 .menu>li:not(:last-child){margin:0 0 var(--main-gap,1.5rem)!important}}<\/style><\/nav><\/div><\/div><\/div><div class=\"vc_col-sm-8 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>CONDITIONS G\u00c9N\u00c9RALES<\/h2>\n<\/div><\/div><div class=\"wpb_text_column us_custom_432d3f53\"><div class=\"wpb_wrapper\"><p><em>Modalit\u00e9s d\u2019intervention et honoraires (applicables \u00e0 partir du 1<sup>er<\/sup><span>\u00a0<\/span>d\u00e9cembre 2019)<\/em><\/p>\n<p><strong>Article 1. \u2013<span>\u00a0<\/span><u>Champ d\u2019application<\/u><\/strong><\/p>\n<p>Les pr\u00e9sentes dispositions pr\u00e9cisent les modalit\u00e9s d\u2019intervention de tout avocat associ\u00e9, collaborateur ou stagiaire de soci\u00e9t\u00e9 d\u2019avocats DALDEWOLF RDC (ci-apr\u00e8s: DALDEWOLF),\u00a0 en ce compris \u00a0la fixation des\u00a0 honoraires, frais et\u00a0 d\u00e9bours dus \u00e0 celle-ci.<\/p>\n<p>Lorsqu\u2019un client fait appel aux services de DALDEWOLF, il est r\u00e9put\u00e9 conna\u00eetre et accepter sans r\u00e9serves les pr\u00e9sentes conditions g\u00e9n\u00e9rales.<\/p>\n<p>D\u2019\u00e9ventuelles conditions g\u00e9n\u00e9rales contraires ne seront applicables que moyennant acceptation expresse, pr\u00e9alable et \u00e9crite de DALDEWOLF.<\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales s\u2019appliqueront \u00e9galement \u00e0 toutes les relations futures entre parties.<\/p>\n<p>Tout compl\u00e9ment, modification ou d\u00e9rogation doit \u00eatre express\u00e9ment accept\u00e9 par \u00e9crit par DALDEWOLF.<\/p>\n<p><strong>Article 2. \u2013<span>\u00a0<\/span><u>Mission de DALDEWOLF<\/u><\/strong><\/p>\n<ul>\n<li>Le client charge DALDEWOLF de la d\u00e9fense des int\u00e9r\u00eats qu\u2019il lui La mission de l\u2019avocat consiste \u00e0 conseiller, assister ou repr\u00e9senter le client. Elle\u00a0 comprend \u00a0toutes \u00a0les \u00a0prestations accomplies \u00e0 cet effet.<\/li>\n<\/ul>\n<p>Avant d\u2019accepter une mission, DALDEWOLF :<\/p>\n<ul>\n<li>proc\u00e8de \u00e0 la v\u00e9rification de l\u2019absence de conflit d\u2019int\u00e9r\u00eats. En cas de conflit, DALDEWOLF refuse la mission ;<\/li>\n<li>prend toute mesure utile afin de se conformer \u00e0 la l\u00e9gislation relative \u00e0 la lutte contre le blanchiment d\u2019argent (voir article 17). Le client s\u2019engage \u00e0 fournir l\u2019ensemble des informations et \u00e0 prendre tout engagement requis \u00e0 cet A d\u00e9faut d\u2019avoir recueilli lesdits engagements et informations, DALDEWOLF refuse la mission.<\/li>\n<li>L\u2019associ\u00e9 de DALDEWOLF en charge du dossier se\u00a0 r\u00e9serve, \u00e0\u00a0 l\u2019occasion\u00a0 de\u00a0 l\u2019ex\u00e9cution de cette mission, de\u00a0 faire appel, sous sa responsabilit\u00e9, \u00e0 un ou plusieurs associ\u00e9s, collaborateurs ou<\/li>\n<\/ul>\n<p>DALDEWOLF est en droit de faire appel \u00e0 des tiers\u00a0 non-avocats\u00a0 (comme des\u00a0 huissiers\u00a0 de\u00a0 justice, conseils techniques, etc.) en vue de\u00a0 l\u2019ex\u00e9cution\u00a0 de\u00a0 ses activit\u00e9s.\u00a0 DALDEWOLF\u00a0 s\u2019engage \u00e0 choisir\u00a0 ces tiers avec discernement mais n\u2019est en aucun cas responsable des actes ou n\u00e9gligences de ceux-ci. DALDEWOLF est autoris\u00e9e par le client \u00e0 accepter au nom de celui-ci d\u2019\u00e9ventuelles limitations de responsabilit\u00e9 de ces tiers.<\/p>\n<p>DALDEWOLF agit avec diligence, au mieux des int\u00e9r\u00eats du client, sans toutefois pouvoir garantir le r\u00e9sultat esp\u00e9r\u00e9.<\/p>\n<p>L\u2019attention du client est attir\u00e9e sur le fait qu\u2019en cas de litige :<\/p>\n<ul>\n<li>la r\u00e9p\u00e9tibilit\u00e9 des honoraires peut obliger le client\u00a0 d\u00e9bout\u00e9 de son action\u00a0 ou\u00a0 qui succombe \u00a0aux demandes de la partie adverse \u00e0 payer des indemnit\u00e9s de proc\u00e9dure ;<\/li>\n<li>des droits proportionnels peuvent \u00e9galement \u00eatre dus, en fonction des<\/li>\n<li>Le client informe DALDEWOLF, de la mani\u00e8re la plus compl\u00e8te possible, de\u00a0 l\u2019ensemble des faits pertinents et\u00a0 lui\u00a0 communique\u00a0 tous les \u00e9l\u00e9ments et\u00a0 documents\u00a0 utiles en\u00a0 sa\u00a0 possession au d\u00e9but du dossier et tout au long de la mission, en particulier, lors de tout nouveau d\u00e9veloppement ou changement de Il remet \u00e0 DALDEWOLF\u00a0 tout\u00a0 acte\u00a0 de proc\u00e9dure, exploit d\u2019huissier, lettre de mise en demeure ou document de toute nature qui lui est signifi\u00e9 ou notifi\u00e9 d\u00e8s sa r\u00e9ception. Le client informe \u00e9galement \u00a0DALDEWOLF\u00a0 de\u00a0 la souscription\u00a0 \u00e9ventuelle d\u2019une assurance de\u00a0 protection\u00a0 juridique\u00a0 et\u00a0 transmet\u00a0 \u00e0\u00a0 DALDEWOLF les coordonn\u00e9es de celle-ci.<\/li>\n<\/ul>\n<p>2.5\u00a0\u00a0 \u00a0DALDEWOLF attire l\u2019attention\u00a0 du client sur la\u00a0 possibilit\u00e9 de\u00a0 r\u00e9soudre les diff\u00e9rends par des voies autres que le contentieux judiciaire, telles que la m\u00e9diation, la conciliation ou tout autre mode de r\u00e9solution amiable des litiges. DALDEWOLF consid\u00e8re qu\u2019il entre dans sa mission de les recommander, de les favoriser et de les mettre en \u0153uvre dans la mesure du possible, et ce \u00e0 tout stade de la gestion d\u2019un dossier.<\/p>\n<p>2.6.\u00a0\u00a0 \u00a0Sauf indication contraire expr\u00e8s du client, DALDEWOLF communiquera avec le client par tout moyen standard et appropri\u00e9, tel que le courrier \u00e9lectronique et le t\u00e9l\u00e9phone. Il est de la responsabilit\u00e9 du client de s\u2019assurer que les adresses emails qu\u2019il a communiqu\u00e9s \u00e0 DALDEWOLF pr\u00e9sentent un degr\u00e9 de s\u00e9curit\u00e9 suffisant contre toute atteinte informatique malveillante ou accidentelle. DALDEWOLF ne pourra pas \u00eatre tenue responsable des dommages qui pourront r\u00e9sulter de l\u2019utilisation d\u2019adresses emails de clients qui pr\u00e9sentent un niveau de s\u00e9curit\u00e9 absent ou insuffisant contre toute atteinte informatique malveillante ou accidentelle.<\/p>\n<p><strong>Article 3. \u2013<span>\u00a0<\/span><u>Fin anticip\u00e9e de la mission<\/u><\/strong><\/p>\n<p>Chaque partie a le droit de mettre fin \u00e0 la mission de l\u2019avocat \u00e0 tout moment,\u00a0 sans avoir\u00a0 \u00e0\u00a0 en justifier le motif.<\/p>\n<p>Dans ce cas, les pi\u00e8ces remises par le client \u00e0 DALDEWOLF sont restitu\u00e9es\u00a0 \u00e0\u00a0 celui-ci \u00a0ou transmises \u00e0 son nouveau conseil, sauf si le client en demande express\u00e9ment la destruction.<\/p>\n<p>Les honoraires, frais et d\u00e9bours de DALDEWOLF sont dus par le client pour les prestations accomplies jusqu\u2019au jour o\u00f9 la mission prend fin.<\/p>\n<p><strong>Article 4. \u2013<span>\u00a0<\/span><u>Etat d\u2019honoraires, frais et d\u00e9bours<\/u><\/strong><\/p>\n<ul>\n<li>Sauf convention \u00e9crite contraire, les honoraires, frais et d\u00e9bours dus \u00e0 DALDEWOLF sont fix\u00e9s et dus conform\u00e9ment aux pr\u00e9sentes<\/li>\n<li>A l\u2019ouverture du dossier, une provision d\u2019honoraires est constitu\u00e9e et peut \u00eatre renouvel\u00e9e en fonction des besoins du dossier.<\/li>\n<\/ul>\n<p><strong>Article 5. \u2013<span>\u00a0<\/span><u>Calcul des honoraires<\/u><\/strong><\/p>\n<p>Sauf \u00e0 avoir convenu avec le client d\u2019un autre mode de calcul fix\u00e9 dans la lettre d\u2019engagement sign\u00e9e avec lui, les honoraires sont fonction du nombre\u00a0 d\u2019heures\u00a0 consacr\u00e9es\u00a0 par\u00a0 DALDEWOLF\u00a0 au dossier.\u00a0 Entrent\u00a0 notamment\u00a0 en compte \u00e0 cet \u00e9gard:<\/p>\n<ul>\n<li>l\u2019examen des pi\u00e8ces du dossier et des courriers re\u00e7us;<\/li>\n<li>l\u2019analyse juridique, en ce compris les recherches, la r\u00e9daction ou la relecture de tout document (correspondance, avis \u00e9crit, consultations \u00e9crites, actes de proc\u00e9dures, conventions, m\u00e9moires ou notes) \u00e0 r\u00e9diger dans le cadre de l\u2019affaire;<\/li>\n<li>les r\u00e9unions et entretiens t\u00e9l\u00e9phoniques avec le client ou avec les tiers en ce compris les avis oraux;<\/li>\n<li>les d\u00e9marches administratives, les plaidoiries, l\u2019assistance \u00e0 toute audience, r\u00e9union ou autre s\u00e9ance, en ce compris la pr\u00e9paration de ces devoirs ;<\/li>\n<li>les d\u00e9placements et les temps d\u2019attente.<\/li>\n<\/ul>\n<p>Si plusieurs avocats interviennent, les dur\u00e9es de leurs prestations respectives sont cumul\u00e9es.<\/p>\n<p><strong>Article 6. \u2013<span>\u00a0<\/span><u>Taux horaire<\/u><\/strong><\/p>\n<p>Le taux horaire annonc\u00e9 hors TVA est d\u00e9termin\u00e9 \u00e0 l\u2019ouverture du dossier ou d\u2019un ensemble de dossiers et pr\u00e9cis\u00e9 par \u00e9crit.<\/p>\n<p><strong>Article 7. \u2013<span>\u00a0<\/span><u>Honoraire de r\u00e9sultat<\/u><\/strong><\/p>\n<ul>\n<li>Les parties peuvent convenir qu\u2019\u00e0 la fin de la mission DALDEWOLF prendra en compte un honoraire de r\u00e9sultat en cas de gain m\u00eame partiel du litige ou en cas de conclusion d\u2019une convention n\u00e9goci\u00e9e en tout ou partie pour le<\/li>\n<li>Les modalit\u00e9s de calcul de l\u2019honoraire de r\u00e9sultat seront convenues entre<\/li>\n<\/ul>\n<p><strong>Article 8. \u2013<span>\u00a0<\/span><u>Paiement et int\u00e9r\u00eats moratoires<\/u><\/strong><\/p>\n<ul>\n<li>Les demandes de provision, les \u00e9tats interm\u00e9diaires et les \u00e9tats d\u2019honoraires sont payables \u00e0 r\u00e9ception, et au plus tard le 30\u00e8me jour suivant la date d\u2019envoi. A l\u2019expiration de ce d\u00e9lai, des int\u00e9r\u00eats de retard sont dus \u00e0 hauteur de 12 % l\u2019an.<\/li>\n<li>En cas de\u00a0 non-paiement dans le d\u00e9lai,\u00a0 DALDEWOLF suspendra\u00a0 l\u2019ex\u00e9cution de sa mission, huit (08) jours calendrier apr\u00e8s avoir notifi\u00e9 sa d\u00e9cision au client, en mentionnant les cons\u00e9quences qui peuvent en r\u00e9sulter.<\/li>\n<\/ul>\n<p><strong>Article 9. \u2013<span>\u00a0<\/span><u>Indexation et modification<\/u><\/strong><\/p>\n<p>Sauf convention contraire \u00e9tablie entre le client et DALDEWOLF, DALDEWOLF facture ses prestations, frais et \u00e9ventuels d\u00e9bours sur la base des taux convenus. Ces taux peuvent \u00eatre adapt\u00e9s en fonction de l\u2019\u00e9volution du march\u00e9 et seront applicables entre parties trois mois apr\u00e8s notification des taux adapt\u00e9s.<\/p>\n<p>Sauf accord du client, DALDEWOLF ne change pas de m\u00e9thode de calcul des honoraires, frais et \u00a0d\u00e9bours pendant le cours du dossier.<\/p>\n<p><strong>Article 10. \u2013<span>\u00a0<\/span><u>Frais<\/u><\/strong><\/p>\n<ul>\n<li>Les frais sont dus, en outre ils couvrent:<\/li>\n<li>l\u2019ouverture de dossier<\/li>\n<li>frais de secr\u00e9tariat<\/li>\n<li>autres frais de fonctionnement<\/li>\n<\/ul>\n<p>10.2. \u00a0\u00a0\u00a0\u00a0 Les frais vis\u00e9s \u00e0 l\u2019article 10.1 sont factur\u00e9s forfaitairement, sauf convention contraire expresse, \u00e0 concurrence de 05 (cinq) % du\u00a0 montant des\u00a0 honoraires\u00a0 factur\u00e9s.\u00a0 Les autres frais et d\u00e9bours sont factur\u00e9s au client \u00e0 prix co\u00fbtant.<\/p>\n<p><strong>Article 11. \u2013<span>\u00a0<\/span><u>D\u00e9bours<\/u><\/strong><\/p>\n<p>11.1. Les d\u00e9bours sont constitu\u00e9s par les frais que DALDEWOLF a support\u00e9s pour le compte du client, entre autres :<\/p>\n<ul>\n<li>les frais d\u2019huissier;<\/li>\n<li>les frais de greffe et de justice;<\/li>\n<li>les frais de procuration notariale;<\/li>\n<li>les provisions et honoraires de correspondants;<\/li>\n<li>les frais de recherche sp\u00e9cifique (documentation l\u00e9gale et administrative, par exemple);<\/li>\n<li>les frais de d\u00e9placement et de s\u00e9jour extraordinaires (avion, train, h\u00f4tels, );<\/li>\n<li>les frais de traductions;<\/li>\n<li>les frais de conseils techniques;<\/li>\n<li>les frais d\u2019envoi de colis ou de courriers sp\u00e9ciaux ou<\/li>\n<\/ul>\n<p>11.2. Le client s\u2019engage \u00e0 rembourser les d\u00e9bours sur simple demande. DALDEWOLF produit \u00e0 la demande du client les justificatifs lorsque ceux-ci existent. Une provision sp\u00e9cifique peut \u00eatre demand\u00e9e au client pour les d\u00e9bours importants.<\/p>\n<p>11.3. Sauf accord contraire, le client prend les d\u00e9bours directement en charge.<\/p>\n<p><strong>Article 12. \u2013<span>\u00a0<\/span><u>Secret professionnel et confidentialit\u00e9<\/u><\/strong><\/p>\n<p>Les avocats du cabinet DALDEWOLF sont soumis au secret professionnel.<\/p>\n<p>L\u2019ensemble des courriers, avis, \u00e9crits de proc\u00e9dure, etc., transmis par DALDEWOLF au client le sont sous la condition expresse que le client en respecte la confidentialit\u00e9. Le client ne peut en transmettre le contenu \u00e0 des tiers que moyennant l\u2019accord expr\u00e8s, pr\u00e9alable et \u00e9crit de DALDEWOLF.<\/p>\n<p>Lorsqu\u2019elle r\u00e9pond \u00e0 un march\u00e9 public ou \u00e0 un appel d\u2019offre priv\u00e9 de services juridiques, DALDEWOLF peut \u00eatre amen\u00e9, dans le strict respect des r\u00e8gles d\u00e9ontologiques de l\u2019avocat, \u00e0 r\u00e9v\u00e9ler le nom des\u00a0 clients pour lesquels elle intervient ou est intervenue dans la mati\u00e8re concern\u00e9e, de m\u00eame qu\u2019elle peut fournir des informations en rapport avec l\u2019objet du march\u00e9 dans les dossiers qu\u2019elle traite ou a trait\u00e9s. Les informations communiqu\u00e9es n\u2019ont, en aucun cas, trait \u00e0 la vie priv\u00e9e du client. Le client marque son accord, r\u00e9vocable \u00e0 tout moment, sur cette communication.<\/p>\n<p><strong>Article 13. \u2013<span>\u00a0<\/span><u>Responsabilit\u00e9<\/u><span>\u00a0<\/span><u>professionnelle<\/u><\/strong><\/p>\n<p>La responsabilit\u00e9 civile professionnelle de DALDEWOLF, s\u2019il \u00e9chet, est limit\u00e9e \u00e0 l\u2019\u00e9quivalent de trois (03) fois le montant des honoraires encaiss\u00e9s.<\/p>\n<p><strong>Article 14. \u2013<span>\u00a0<\/span><u>Divisibilit\u00e9<\/u><\/strong><\/p>\n<p>Au cas o\u00f9 une des clauses ou une partie d\u2019une des clauses des pr\u00e9sentes conditions g\u00e9n\u00e9rales serait d\u00e9clar\u00e9e nulle ou non applicable, toutes les autres clauses resteront d\u2019application.<\/p>\n<p><strong>Article 15. \u2013<span>\u00a0<\/span><u>Traitement des donn\u00e9es personnelles<\/u><\/strong><\/p>\n<p>15.1. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 DALDEWOLF\u00a0\u00a0\u00a0\u00a0\u00a0 traite\u00a0\u00a0 \u00a0les\u00a0 \u00a0donn\u00e9es\u00a0 \u00a0\u00e0\u00a0 \u00a0caract\u00e8re\u00a0\u00a0\u00a0 personnel\u00a0\u00a0\u00a0\u00a0 (\u00ab donn\u00e9es\u00a0\u00a0\u00a0\u00a0\u00a0 personnelles\u00bb) conform\u00e9ment aux dispositions du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (R\u00e8glement N\u00b0 2016\/679). Elle agit en tant que responsable du traitement lorsqu\u2019elle traite les \u00a0\u00a0donn\u00e9es personnelles de ses clients, adversaires, autres avocats, juges, huissiers de justice, clients potentiels, fournisseurs, partenaires, candidats ou autres parties tierces (\u00ab personnes concern\u00e9es\u00bb). DALDEWOLF utilise les donn\u00e9es personnelles fournies, telles que, par exemple le nom, l\u2019adresse email, l\u2019adresse, le num\u00e9ro de t\u00e9l\u00e9phone et les informations relatives au dossier du client.<\/p>\n<p>15.2. \u00a0\u00a0\u00a0\u00a0\u00a0 DALDEWOLF traite les donn\u00e9es personnelles pour plusieurs finalit\u00e9s, telles que le traitement\u00a0du dossier, la facturation de ses services, le recouvrement de cr\u00e9ances si n\u00e9cessaire, l\u2019archivage et la suppression des donn\u00e9es, dans le cadre de l\u2019ex\u00e9cution du contrat conclu avec le client. Si une personne physique repr\u00e9sente une soci\u00e9t\u00e9 qui est\u00a0 le client, DALDEWOLF\u00a0 peut traiter les donn\u00e9es personnelles d\u2019une personne\u00a0 physique\u00a0 repr\u00e9sentant\u00a0 une soci\u00e9t\u00e9 cliente sur\u00a0 la\u00a0 base des\u00a0 int\u00e9r\u00eats l\u00e9gitimes du\u00a0 client et de DALDEWOLF (\u00e0 savoir, afin de fournir les services pour lesquels le client a fait appel \u00e0 DALDEWOLF).<\/p>\n<p>15.3. \u00a0\u00a0\u00a0\u00a0\u00a0 DALDEWOLF peut transf\u00e9rer des donn\u00e9es personnelles vers des parties tierces (tels que les tribunaux, huissiers, adversaires, sous-traitants tels que les fournisseurs de services\u00a0 IT)\u00a0 lorsque\u00a0 les dossiers l\u2019exigent.<\/p>\n<p>15.4. \u00a0\u00a0\u00a0\u00a0 Les donn\u00e9es personnelles qui sont sous le contr\u00f4le de\u00a0 DALDEWOLF peuvent \u00eatre transf\u00e9r\u00e9es \u00a0\u00e0 des sous-traitants (tels que des fournisseurs de services IT ou autres consultants) ou \u00e0 d\u2019autres responsables du traitement (p.ex. d\u2019autres avocats) lorsque cela est n\u00e9cessaire dans le cadre du traitement des dossiers des clients.<\/p>\n<p>15.5. \u00a0\u00a0\u00a0\u00a0\u00a0 DALDEWOLF conserve les donn\u00e9es personnelles relatives aux dossiers des clients aussi longtemps qu\u2019il est\u00a0 trait\u00e9. DALDEWOLF proc\u00e8de \u00e0 l\u2019archivage du dossier (et des donn\u00e9es personnelles qu\u2019il contient) lors de sa cl\u00f4ture et le d\u00e9truit \u00e0 l\u2019expiration d\u2019un d\u00e9lai de cinq ans apr\u00e8s sa cl\u00f4ture (\u00e0 moins qu\u2019un diff\u00e9rend soit n\u00e9 et que\u00a0 DALDEWOLF ait besoin\u00a0 des\u00a0 donn\u00e9es\u00a0 pour assurer la d\u00e9fense de ses droits). En vertu des r\u00e8gles professionnelles, DALDEWOLF doit conserver certaines donn\u00e9es (comme l\u2019identit\u00e9 des\u00a0 clients) afin de\u00a0 v\u00e9rifier les conflits d\u2019int\u00e9r\u00eats et d\u2019assurer le respect du secret professionnel, qui est imprescriptible.<\/p>\n<p>15.6. \u00a0\u00a0\u00a0\u00a0 DALDEWOLF s\u2019engage \u00e0 respecter les droits de la personne concern\u00e9e,\u00a0 qui\u00a0 peut exercer ses droits et \u00a0prendre contact en envoyant \u00a0un email \u00e0 l\u2019adresse<span>\u00a0<\/span><a href=\"mailto:dataprotection@daldewolf.com\">dataprotection@daldewolf.com<\/a>.<\/p>\n<p><strong>Article 16 \u2013<span>\u00a0<\/span><u>Pr\u00e9vention du blanchiment des capitaux et du financement du terrorisme<\/u><\/strong><\/p>\n<p>16.1. \u00a0\u00a0\u00a0\u00a0\u00a0 DALDEWOLF se conforme \u00e0 ses obligations l\u00e9gales en mati\u00e8re d\u2019identification du client ou de son mandant. Ce dernier s\u2019engage \u00e0 fournir spontan\u00e9ment\u00a0 tous documents\u00a0 permettant l\u2019\u00e9tablissement de l\u2019identit\u00e9 et autorise l\u2019avocat \u00e0 en prendre copie.<\/p>\n<p>Les obligations de DALDEWOLF et du client d\u00e9coulent des lois et r\u00e8glements congolaises et belge, DALDEWOLF RDC \u00e9tant filiale de la soci\u00e9t\u00e9 d\u2019avocats \u00e0 responsabilit\u00e9 limit\u00e9e DALDEWOLF SRL, et notamment des dispositions de la loi du 18 septembre 2017 relative \u00e0 la pr\u00e9vention du blanchiment des capitaux et du financement du terrorisme, qui s\u2019applique notamment lorsque l\u2019avocat assiste son\u00a0 client\u00a0 dans\u00a0 la pr\u00e9paration d\u2019op\u00e9rations sp\u00e9cifiques telles que: assistance du client dans la pr\u00e9paration ou la r\u00e9alisation d\u2019op\u00e9rations telles qu\u2019 achat ou vente d\u2019immeubles ou d\u2019entreprises commerciales ;\u00a0 gestion\u00a0 de fonds de titres ou d\u2019autres actifs appartenant aux clients ou \u00e0 son mandant; ouverture ou gestion de comptes bancaires, d\u2019\u00e9pargne ou de portefeuilles; organisation des apports n\u00e9cessaires \u00e0\u00a0 la\u00a0 constitution,\u00a0 \u00e0\u00a0 la gestion ou \u00e0 la direction de soci\u00e9t\u00e9s; constitution, gestion ou direction de fiducies, de soci\u00e9t\u00e9s ou de structures similaires ou interventions au nom et pour compte du client dans toutes transactions financi\u00e8res et immobili\u00e8res. Les renseignements qui doivent \u00eatre exig\u00e9s par DALDEWOLF de la part de son client varient selon qu\u2019il s\u2019agit d\u2019une personne physique, d\u2019une personne morale, ou d\u2019un mandataire. Le client informera\u00a0 au plus vite et spontan\u00e9ment\u00a0 DALDEWOLF de toute modification et lui apportera la preuve de celle-ci.<\/p>\n<p>16.2. \u00a0\u00a0\u00a0\u00a0\u00a0 Lorsque la nature du dossier (telle que d\u00e9finie au point 16.1) ou lorsque les situations particuli\u00e8res pr\u00e9vues par la loi pr\u00e9cit\u00e9e du 18 septembre 2017 (pays d\u2019origine, difficult\u00e9s d\u2019identification, relation inusuelle entre le client et DALDEWOLF ou la nature des op\u00e9rations, personnalit\u00e9 publique ou assimil\u00e9e) imposent \u00e0 DALDEWOLF une obligation de vigilance renforc\u00e9e, le client s\u2019engage \u00e0 r\u00e9pondre \u00e0 toute question de DALDEWOLF lui permettant\u00a0 de se conformer \u00e0 ses obligations l\u00e9gales en mati\u00e8re de lutte contre le blanchiment des capitaux et le financement du terrorisme.<\/p>\n<p>16.3. \u00a0\u00a0\u00a0\u00a0\u00a0 Lorsque DALDEWOLF assiste le client dans sa d\u00e9fense en justice ou lorsqu\u2019il proc\u00e8de \u00e0 l\u2019\u00e9valuation de sa situation juridique, DALDEWOLF est tenue au strict respect du secret professionnel. Il est pr\u00e9cis\u00e9 que la loi impose \u00e0 l\u2019avocat d\u2019informer le b\u00e2tonnier d\u00e8s qu\u2019il constate, hors sa mission de d\u00e9fense en justice ou de consultation relative \u00e0 l\u2019analyse de la situation juridique du client, des faits qu\u2019il \u00a0soup\u00e7onne d\u2019\u00eatre li\u00e9s au blanchiment des capitaux ou au financement du terrorisme.<\/p>\n<p><strong>Article 17. \u2013 \u00a0<u>Droit applicable<\/u><\/strong><\/p>\n<p>Le droit congolais est applicable aux relations entre parties, sauf l\u2019application additionnelle du droit belge, en tant que filiale d\u2019une soci\u00e9t\u00e9 d\u2019avocats belge, en mati\u00e8re de lutte contre le blanchiment de capitaux et le financement du terrorisme, tel que vis\u00e9 \u00e0 l\u2019article 16 ci-dessus.<\/p>\n<p><strong>Article 18. \u2013<span>\u00a0<\/span><u>Arbitrage et juridiction comp\u00e9tente<\/u><\/strong><\/p>\n<p>18.1. En cas de litige de nature d\u00e9ontologique ou d\u2019honoraires, les parties saisiront le B\u00e2tonnier de l\u2019Ordre des avocats du barreau de Kinshasa\/Matete.<\/p>\n<p>18.2. En cas de litige d\u2019une autre nature, notamment en mati\u00e8re de responsabilit\u00e9 civile, tout diff\u00e9rend est de la comp\u00e9tence exclusive des juridictions de Kinshasa\/Gombe.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"\u00c0 PROPOS DE DALDEWOLF EN RDC Le cabinet et son approcheComment nous pouvons aiderL\u2019\u00e9quipeContactConditions g\u00e9n\u00e9ralesAUTRES PAYS AFRICAINS ContactCONDITIONS G\u00c9N\u00c9RALES Modalit\u00e9s d\u2019intervention et honoraires (applicables \u00e0 partir du 1er\u00a0d\u00e9cembre 2019) Article 1. \u2013\u00a0Champ d\u2019application Les pr\u00e9sentes dispositions pr\u00e9cisent les modalit\u00e9s d\u2019intervention de tout avocat associ\u00e9, collaborateur ou stagiaire de soci\u00e9t\u00e9 d\u2019avocats DALDEWOLF RDC (ci-apr\u00e8s: DALDEWOLF),\u00a0 en...","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15596","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DALDEWOLF en RDC - Conditions G\u00e9n\u00e9rales - DALDEWOLF<\/title>\n<meta name=\"description\" content=\"Modalit\u00e9s d\u2019intervention et honoraires de DALDEWOLF en RDC (applicables \u00e0 partir du 1er d\u00e9cembre 2019)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DALDEWOLF en RDC - Conditions G\u00e9n\u00e9rales - DALDEWOLF\" \/>\n<meta property=\"og:description\" content=\"Modalit\u00e9s d\u2019intervention et honoraires de DALDEWOLF en RDC (applicables \u00e0 partir du 1er d\u00e9cembre 2019)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/\" \/>\n<meta property=\"og:site_name\" content=\"DALDEWOLF\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T09:49:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2021\/05\/Daldewolf-fb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/daldewolf-en-rdc-conditions-generales\\\/\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/daldewolf-en-rdc-conditions-generales\\\/\",\"name\":\"DALDEWOLF en RDC - Conditions G\u00e9n\u00e9rales - DALDEWOLF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#website\"},\"datePublished\":\"2024-10-14T15:45:03+00:00\",\"dateModified\":\"2024-10-15T09:49:01+00:00\",\"description\":\"Modalit\u00e9s d\u2019intervention et honoraires de DALDEWOLF en RDC (applicables \u00e0 partir du 1er d\u00e9cembre 2019)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/daldewolf-en-rdc-conditions-generales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/daldewolf-en-rdc-conditions-generales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/daldewolf-en-rdc-conditions-generales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.daldewolf.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DALDEWOLF en RDC &#8211; Conditions G\u00e9n\u00e9rales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/\",\"name\":\"DALDEWOLF\",\"description\":\"Independant Law firm, Since 1958.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#organization\",\"name\":\"DALDEWOLF\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Daldewolf.png\",\"contentUrl\":\"https:\\\/\\\/www.daldewolf.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo-Daldewolf.png\",\"width\":320,\"height\":40,\"caption\":\"DALDEWOLF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daldewolf.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10193320\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DALDEWOLF en RDC - Conditions G\u00e9n\u00e9rales - DALDEWOLF","description":"Modalit\u00e9s d\u2019intervention et honoraires de DALDEWOLF en RDC (applicables \u00e0 partir du 1er d\u00e9cembre 2019)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/","og_locale":"fr_FR","og_type":"article","og_title":"DALDEWOLF en RDC - Conditions G\u00e9n\u00e9rales - DALDEWOLF","og_description":"Modalit\u00e9s d\u2019intervention et honoraires de DALDEWOLF en RDC (applicables \u00e0 partir du 1er d\u00e9cembre 2019)","og_url":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/","og_site_name":"DALDEWOLF","article_modified_time":"2024-10-15T09:49:01+00:00","og_image":[{"width":600,"height":315,"url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2021\/05\/Daldewolf-fb.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/","url":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/","name":"DALDEWOLF en RDC - Conditions G\u00e9n\u00e9rales - DALDEWOLF","isPartOf":{"@id":"https:\/\/www.daldewolf.com\/nl\/#website"},"datePublished":"2024-10-14T15:45:03+00:00","dateModified":"2024-10-15T09:49:01+00:00","description":"Modalit\u00e9s d\u2019intervention et honoraires de DALDEWOLF en RDC (applicables \u00e0 partir du 1er d\u00e9cembre 2019)","breadcrumb":{"@id":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.daldewolf.com\/fr\/daldewolf-en-rdc-conditions-generales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.daldewolf.com\/fr\/"},{"@type":"ListItem","position":2,"name":"DALDEWOLF en RDC &#8211; Conditions G\u00e9n\u00e9rales"}]},{"@type":"WebSite","@id":"https:\/\/www.daldewolf.com\/nl\/#website","url":"https:\/\/www.daldewolf.com\/nl\/","name":"DALDEWOLF","description":"Independant Law firm, Since 1958.","publisher":{"@id":"https:\/\/www.daldewolf.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.daldewolf.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.daldewolf.com\/nl\/#organization","name":"DALDEWOLF","url":"https:\/\/www.daldewolf.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/Logo-Daldewolf.png","contentUrl":"https:\/\/www.daldewolf.com\/wp-content\/uploads\/2020\/05\/Logo-Daldewolf.png","width":320,"height":40,"caption":"DALDEWOLF"},"image":{"@id":"https:\/\/www.daldewolf.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/10193320"]}]}},"_links":{"self":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/pages\/15596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/comments?post=15596"}],"version-history":[{"count":0,"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/pages\/15596\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.daldewolf.com\/fr\/wp-json\/wp\/v2\/media?parent=15596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}